{"id":2667,"count":0,"description":"","link":"https:\/\/ramsesegypt.com\/es\/tag\/king-ramses-iii-pl\/","name":"King Ramses III","slug":"king-ramses-iii-pl","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/ramsesegypt.com\/es\/wp-json\/wp\/v2\/tags\/2667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramsesegypt.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ramsesegypt.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ramsesegypt.com\/es\/wp-json\/wp\/v2\/posts?tags=2667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}